{"id":84,"name":"Melissa Geraghty, PsyD","url":"","description":"Dr. Melissa Geraghty, Psy.D. is a Licensed Clinical Health Psychologist and Stanford-trained Certified Empowered Relief\u2122 Instructor. Dr. Geraghty has received recognition for her clinical excellence and patient advocacy as a Keynote and International Speaker.","link":"https:\/\/betterme.world\/articles\/author\/dr-melissa-geraghty\/","slug":"dr-melissa-geraghty","avatar_urls":{"24":"https:\/\/cdn.betterme.world\/articles\/wp-content\/uploads\/2024\/03\/melissa-150x150.png","48":"https:\/\/cdn.betterme.world\/articles\/wp-content\/uploads\/2024\/03\/melissa-150x150.png","96":"https:\/\/cdn.betterme.world\/articles\/wp-content\/uploads\/2024\/03\/melissa-150x150.png"},"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.2.1 (Yoast SEO v25.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Melissa Geraghty, PsyD<\/title>\n<meta name=\"description\" content=\"Dr. Melissa Geraghty, Psy.D. is a Licensed Clinical Health Psychologist and Stanford-trained Certified Empowered Relief\u2122 Instructor. Dr. Geraghty has received recognition for her clinical excellence and patient advocacy as a Keynote and International Speaker.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/betterme.world\/articles\/author\/dr-melissa-geraghty\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Melissa Geraghty, PsyD\" \/>\n<meta property=\"og:description\" content=\"Dr. Melissa Geraghty, Psy.D. is a Licensed Clinical Health Psychologist and Stanford-trained Certified Empowered Relief\u2122 Instructor. Dr. Geraghty has received recognition for her clinical excellence and patient advocacy as a Keynote and International Speaker.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/betterme.world\/articles\/author\/dr-melissa-geraghty\/\" \/>\n<meta property=\"og:site_name\" content=\"BetterMe Blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.betterme.world\/articles\/wp-content\/uploads\/2024\/03\/melissa.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@betterme\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\/\/betterme.world\/articles\/author\/dr-melissa-geraghty\/\",\"url\":\"https:\/\/betterme.world\/articles\/author\/dr-melissa-geraghty\/\",\"name\":\"Melissa Geraghty, PsyD\",\"isPartOf\":{\"@id\":\"https:\/\/betterme.world\/articles\/#website\"},\"description\":\"Dr. Melissa Geraghty, Psy.D. is a Licensed Clinical Health Psychologist and Stanford-trained Certified Empowered Relief\u2122 Instructor. Dr. Geraghty has received recognition for her clinical excellence and patient advocacy as a Keynote and International Speaker.\",\"breadcrumb\":{\"@id\":\"https:\/\/betterme.world\/articles\/author\/dr-melissa-geraghty\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/betterme.world\/articles\/author\/dr-melissa-geraghty\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/betterme.world\/articles\/author\/dr-melissa-geraghty\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/betterme.world\/articles\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Melissa Geraghty, PsyD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/betterme.world\/articles\/#website\",\"url\":\"https:\/\/betterme.world\/articles\/\",\"name\":\"BetterMe Blog\",\"description\":\"Health &amp; Fitness\",\"publisher\":{\"@id\":\"https:\/\/betterme.world\/articles\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/betterme.world\/articles\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/betterme.world\/articles\/#organization\",\"name\":\"BetterMe\",\"alternateName\":\"Betterme Limited\",\"url\":\"https:\/\/betterme.world\/articles\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/betterme.world\/articles\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cdn.betterme.world\/articles\/wp-content\/uploads\/2023\/07\/BetterMe.png\",\"contentUrl\":\"https:\/\/cdn.betterme.world\/articles\/wp-content\/uploads\/2023\/07\/BetterMe.png\",\"width\":512,\"height\":512,\"caption\":\"BetterMe\"},\"image\":{\"@id\":\"https:\/\/betterme.world\/articles\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/betterme.health.coaching\",\"https:\/\/x.com\/betterme\",\"https:\/\/www.instagram.com\/betterme\/\",\"https:\/\/www.linkedin.com\/company\/betterme-apps\",\"https:\/\/www.pinterest.com\/bettermetips\/\",\"https:\/\/www.youtube.com\/channel\/UC0svgcjc3jSgcryqo83spPQ\",\"https:\/\/www.tiktok.com\/@betterme.health.coaching\",\"https:\/\/apps.apple.com\/app\/betterme-health-coaching\/id1264546236\",\"https:\/\/play.google.com\/store\/apps\/details?id=com.gen.workoutme&amp;amp;amp;amp;hl=en_US&amp;amp;amp;amp;gl=US\",\"https:\/\/www.wikidata.org\/wiki\/Q114895798\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/betterme.world\/articles\/#\/schema\/person\/21eda304c10e0646f64ca2434fe9663e\",\"name\":\"Melissa Geraghty, PsyD\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/betterme.world\/articles\/#\/schema\/person\/image\/a6a57c5fe3a45ddb38add9abf7b175c2\",\"url\":\"https:\/\/cdn.betterme.world\/articles\/wp-content\/uploads\/2024\/03\/melissa-150x150.png\",\"contentUrl\":\"https:\/\/cdn.betterme.world\/articles\/wp-content\/uploads\/2024\/03\/melissa-150x150.png\",\"caption\":\"Melissa Geraghty, PsyD\"},\"description\":\"Dr. Melissa Geraghty, Psy.D. is a Licensed Clinical Health Psychologist and Stanford-trained Certified Empowered Relief\u2122 Instructor. Dr. Geraghty has received recognition for her clinical excellence and patient advocacy as a Keynote and International Speaker.\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/betterme.world\/articles\/author\/dr-melissa-geraghty\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Melissa Geraghty, PsyD","description":"Dr. Melissa Geraghty, Psy.D. is a Licensed Clinical Health Psychologist and Stanford-trained Certified Empowered Relief\u2122 Instructor. Dr. Geraghty has received recognition for her clinical excellence and patient advocacy as a Keynote and International Speaker.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/betterme.world\/articles\/author\/dr-melissa-geraghty\/","og_locale":"en_US","og_type":"profile","og_title":"Melissa Geraghty, PsyD","og_description":"Dr. Melissa Geraghty, Psy.D. is a Licensed Clinical Health Psychologist and Stanford-trained Certified Empowered Relief\u2122 Instructor. Dr. Geraghty has received recognition for her clinical excellence and patient advocacy as a Keynote and International Speaker.","og_url":"https:\/\/betterme.world\/articles\/author\/dr-melissa-geraghty\/","og_site_name":"BetterMe Blog","og_image":[{"url":"https:\/\/cdn.betterme.world\/articles\/wp-content\/uploads\/2024\/03\/melissa.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@betterme","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/betterme.world\/articles\/author\/dr-melissa-geraghty\/","url":"https:\/\/betterme.world\/articles\/author\/dr-melissa-geraghty\/","name":"Melissa Geraghty, PsyD","isPartOf":{"@id":"https:\/\/betterme.world\/articles\/#website"},"description":"Dr. Melissa Geraghty, Psy.D. is a Licensed Clinical Health Psychologist and Stanford-trained Certified Empowered Relief\u2122 Instructor. Dr. Geraghty has received recognition for her clinical excellence and patient advocacy as a Keynote and International Speaker.","breadcrumb":{"@id":"https:\/\/betterme.world\/articles\/author\/dr-melissa-geraghty\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/betterme.world\/articles\/author\/dr-melissa-geraghty\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/betterme.world\/articles\/author\/dr-melissa-geraghty\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/betterme.world\/articles\/"},{"@type":"ListItem","position":2,"name":"Melissa Geraghty, PsyD"}]},{"@type":"WebSite","@id":"https:\/\/betterme.world\/articles\/#website","url":"https:\/\/betterme.world\/articles\/","name":"BetterMe Blog","description":"Health &amp; Fitness","publisher":{"@id":"https:\/\/betterme.world\/articles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/betterme.world\/articles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/betterme.world\/articles\/#organization","name":"BetterMe","alternateName":"Betterme Limited","url":"https:\/\/betterme.world\/articles\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/betterme.world\/articles\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.betterme.world\/articles\/wp-content\/uploads\/2023\/07\/BetterMe.png","contentUrl":"https:\/\/cdn.betterme.world\/articles\/wp-content\/uploads\/2023\/07\/BetterMe.png","width":512,"height":512,"caption":"BetterMe"},"image":{"@id":"https:\/\/betterme.world\/articles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/betterme.health.coaching","https:\/\/x.com\/betterme","https:\/\/www.instagram.com\/betterme\/","https:\/\/www.linkedin.com\/company\/betterme-apps","https:\/\/www.pinterest.com\/bettermetips\/","https:\/\/www.youtube.com\/channel\/UC0svgcjc3jSgcryqo83spPQ","https:\/\/www.tiktok.com\/@betterme.health.coaching","https:\/\/apps.apple.com\/app\/betterme-health-coaching\/id1264546236","https:\/\/play.google.com\/store\/apps\/details?id=com.gen.workoutme&amp;amp;amp;amp;hl=en_US&amp;amp;amp;amp;gl=US","https:\/\/www.wikidata.org\/wiki\/Q114895798"]},{"@type":"Person","@id":"https:\/\/betterme.world\/articles\/#\/schema\/person\/21eda304c10e0646f64ca2434fe9663e","name":"Melissa Geraghty, PsyD","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/betterme.world\/articles\/#\/schema\/person\/image\/a6a57c5fe3a45ddb38add9abf7b175c2","url":"https:\/\/cdn.betterme.world\/articles\/wp-content\/uploads\/2024\/03\/melissa-150x150.png","contentUrl":"https:\/\/cdn.betterme.world\/articles\/wp-content\/uploads\/2024\/03\/melissa-150x150.png","caption":"Melissa Geraghty, PsyD"},"description":"Dr. Melissa Geraghty, Psy.D. is a Licensed Clinical Health Psychologist and Stanford-trained Certified Empowered Relief\u2122 Instructor. Dr. Geraghty has received recognition for her clinical excellence and patient advocacy as a Keynote and International Speaker.","mainEntityOfPage":{"@id":"https:\/\/betterme.world\/articles\/author\/dr-melissa-geraghty\/"}}]}},"_links":{"self":[{"href":"https:\/\/betterme.world\/articles\/wp-json\/wp\/v2\/users\/84","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/betterme.world\/articles\/wp-json\/wp\/v2\/users"}]}}